  {"id":222,"date":"2019-07-18T13:32:09","date_gmt":"2019-07-18T13:32:09","guid":{"rendered":"https:\/\/www.vanderbilt.edu\/evolution\/?page_id=222"},"modified":"2025-09-12T13:49:49","modified_gmt":"2025-09-12T13:49:49","slug":"advisory-board","status":"publish","type":"page","link":"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/","title":{"rendered":"Evolution@杏吧原创 Leadership &amp; Team"},"content":{"rendered":"<h2>Director<\/h2>\n<div class=\"row\"><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/antonis-rokas\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2019\/05\/19224601\/Antonis_Rokas-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/antonis-rokas\/\">Antonis  Rokas<\/a><\/strong><div class=\"people-title\">Cornelius 杏吧原创 Chair, Department of Biological Sciences<br \/><\/div><div class=\"people-email\"><a href=\"mailto:antonis.rokas@vanderbilt.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><\/div>\n<h2>T32 Leadership<\/h2>\n<div class=\"row\"><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/megan-behringer-2\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2025\/09\/12195346\/Megan-1-142x190.png\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/megan-behringer-2\/\">Megan  Behringer<\/a><\/strong><div class=\"people-title\">T32 Associate Director, CoEvoD<br \/><\/div><div class=\"people-email\"><a href=\"mailto:megan.g.behringer@vanderbilt.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/antonis-rokas-t32\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2024\/02\/27201823\/Antonis_Rokas-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/antonis-rokas-t32\/\">Antonis  Rokas<\/a><\/strong><div class=\"people-title\">T32 Director, CoEvoD<br \/><\/div><div class=\"people-email\"><a href=\"mailto:antonis.rokas@vanderbilt.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/ann-tate-2\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2025\/09\/12194852\/ann-tate-2a-142x190.png\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/ann-tate-2\/\">Ann  Tate<\/a><\/strong><div class=\"people-title\">T32 Advisor, CoEvoD<br \/><\/div><div class=\"people-email\"><a href=\"mailto:a.tate@vanderbilt.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><\/div>\n<h2>Advisory Board<\/h2>\n<div class=\"row\"><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/jada-benn-torres\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2019\/07\/19224559\/BennTorres_Jada-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/jada-benn-torres\/\">Jada  Benn Torres<\/a><\/strong><div class=\"people-title\">Associate Professor, Department of Anthropology<br \/><\/div><div class=\"people-email\"><a href=\"mailto:j.benntor@vanderbilt.edu \"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/larisa-r-g-desantis\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2019\/05\/19224601\/DeSantis_Larisa-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/larisa-r-g-desantis\/\">Larisa  R. G. DeSantis<\/a><\/strong><div class=\"people-title\">Associate Professor, Department of Biological Sciences<br \/><\/div><div class=\"people-email\"><a href=\"mailto:larisa.desantis@杏吧原创.Edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/suzana-herculano-houzel\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2019\/07\/19224557\/Herculano-Houzel_Suzana-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/suzana-herculano-houzel\/\">Suzana  Herculano-Houzel<\/a><\/strong><div class=\"people-title\">Associate Professor, Department of Psychology<br \/><\/div><div class=\"people-email\"><a href=\"mailto:suzana.herculano@vanderbilt.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/owen-d-jones\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2019\/05\/19224601\/Jones_Owen-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/owen-d-jones\/\">Owen D. Jones<\/a><\/strong><div class=\"people-title\">Glenn M. Weaver, M.D. and Mary Ellen Weaver Chair in Law, Brain, and Behavior, Law School<br \/><\/div><div class=\"people-email\"><a href=\"mailto:owen.jones@杏吧原创.Edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/houra-merrikh\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2019\/05\/19224601\/Merrikh_Houra-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/houra-merrikh\/\">Houra  Merrikh<\/a><\/strong><div class=\"people-title\">Professor, Department of Biochemistry<br \/><\/div><div class=\"people-email\"><a href=\"mailto:houra.merrikh@杏吧原创.Edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/1114\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2021\/12\/20023633\/Betsey-Robinson-142x190.jpeg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/1114\/\">Betsey  Robinson<\/a><\/strong><div class=\"people-title\">Associate Professor, Department of History of Art and Architecture<br \/><\/div><div class=\"people-email\"><a href=\"mailto:betsey.a.robinson@vanderbilt.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><\/div>\n<h2>Staff<\/h2>\n<div class=\"row\"><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/theo-danis\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2025\/02\/29151924\/Evolution_2025_0232-142x190.jpeg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/theo-danis\/\">Thodoris  Danis<\/a><\/strong><div class=\"people-title\">Journal Club Coordinator, Evolutionary Studies Initiative<br \/><\/div><div class=\"people-email\"><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/paul-durst\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2022\/04\/17201317\/Durst_picture-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/paul-durst\/\">Paul  Durst<\/a><\/strong><div class=\"people-title\">Educational Programming Chair, Evolutionary Studies<br \/><\/div><div class=\"people-email\"><a href=\"mailto:\tpaul.a.durst@vanderbilt.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/andy-flick\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2021\/12\/20183600\/Andy-Friend-of-Darwin-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/andy-flick\/\">Andy  Flick<\/a><\/strong><div class=\"people-title\">Scientific Coordinator, Evolutionary Studies <br \/><\/div><div class=\"people-email\"><a href=\"mailto:andrew.j.flick@vanderbilt.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/antonis-rokas-1\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2019\/05\/19224601\/Antonis_Rokas-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/antonis-rokas-1\/\">Antonis  Rokas<\/a><\/strong><div class=\"people-title\">Research Chair &amp; T32 Director, Evolutionary Studies<br \/><\/div><div class=\"people-email\"><a href=\"mailto:antonis.rokas@vanderbilt.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/jacob-steenwyk\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2019\/07\/19224120\/Jacob_Steenwyk-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/jacob-steenwyk\/\">Jacob L. Steenwyk<\/a><\/strong><div class=\"people-title\">Chair of Alumni Affairs, Evolutionary Studies<br \/><\/div><div class=\"people-email\"><a href=\"mailto:jlsteenwyk@berkeley.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/brynn-wooten\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2024\/12\/05144113\/PXL_20240420_174113962.MP-1-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/brynn-wooten\/\">Brynn  Wooten<\/a><\/strong><div class=\"people-title\">Chair, Evolution at 杏吧原创 Organization for Students and Trainees<br \/><\/div><div class=\"people-email\"><\/div><\/div><\/div><\/div>\n<h2>Seminar Series Committee<\/h2>\n<div class=\"row\"><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/neil-kelley\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/08\/06160905\/kelley_headshot-300x277-1-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/neil-kelley\/\">Neil  Kelley<\/a><\/strong><div class=\"people-title\">Associate Professor, Earth and Environmental Sciences<br \/><\/div><div class=\"people-email\"><a href=\"mailto:neil.p.kelley@vanderbilt.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/chance-meers\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2025\/09\/11161652\/Chance-Meers-2-e1757607607809-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/chance-meers\/\">Chance  Meers<\/a><\/strong><div class=\"people-title\">Assistant Professor, Department of Biochemistry<br \/><\/div><div class=\"people-email\"><a href=\"mailto:chance.meers@vanderbilt.edu\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i> <\/a><\/div><\/div><\/div><div class=\"col-xs-6 col-sm-4 col-md-3 people-swatch\"><div class=\"people-photo\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/allyson-ray\/\"><img src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2026\/01\/29152733\/PXL_20251010_142352691.MP_-142x190.jpg\" alt=\"image_thumb\" \/><\/a><\/div><div class=\"people-stats\"><strong class=\"people-name\"><a href=\"https:\/\/www.vanderbilt.edu\/evolution\/person\/allyson-ray\/\">Allyson  Ray<\/a><\/strong><div class=\"people-title\">Postdoctoral Fellow, Biological Sciences<br \/><\/div><div class=\"people-email\"><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Director T32 Leadership Advisory Board Staff Seminar Series Committee<\/p>\n","protected":false},"author":1079,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"spay_email":""},"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evolution@杏吧原创 Leadership &amp; Team - Evolution@杏吧原创\" \/>\n<meta property=\"og:description\" content=\"Director T32 Leadership Advisory Board Staff Seminar Series Committee\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolution@杏吧原创\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-12T13:49:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/#website\",\"url\":\"https:\/\/www.vanderbilt.edu\/evolution\/\",\"name\":\"Evolution@杏吧原创\",\"description\":\"Evolutionary Studies Initiative at 杏吧原创\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vanderbilt.edu\/evolution\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/#webpage\",\"url\":\"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/\",\"name\":\"Evolution@杏吧原创 Leadership &amp; Team - Evolution@杏吧原创\",\"isPartOf\":{\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/#website\"},\"datePublished\":\"2019-07-18T13:32:09+00:00\",\"dateModified\":\"2025-09-12T13:49:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vanderbilt.edu\/evolution\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evolution@杏吧原创 Leadership &amp; Team\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/","og_locale":"en_US","og_type":"article","og_title":"Evolution@杏吧原创 Leadership &amp; Team - Evolution@杏吧原创","og_description":"Director T32 Leadership Advisory Board Staff Seminar Series Committee","og_url":"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/","og_site_name":"Evolution@杏吧原创","article_modified_time":"2025-09-12T13:49:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.vanderbilt.edu\/evolution\/#website","url":"https:\/\/www.vanderbilt.edu\/evolution\/","name":"Evolution@杏吧原创","description":"Evolutionary Studies Initiative at 杏吧原创","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vanderbilt.edu\/evolution\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/#webpage","url":"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/","name":"Evolution@杏吧原创 Leadership &amp; Team - Evolution@杏吧原创","isPartOf":{"@id":"https:\/\/www.vanderbilt.edu\/evolution\/#website"},"datePublished":"2019-07-18T13:32:09+00:00","dateModified":"2025-09-12T13:49:49+00:00","breadcrumb":{"@id":"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vanderbilt.edu\/evolution\/advisory-board\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vanderbilt.edu\/evolution\/"},{"@type":"ListItem","position":2,"name":"Evolution@杏吧原创 Leadership &amp; Team"}]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PbblkY-3A","_links":{"self":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/pages\/222"}],"collection":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/users\/1079"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/comments?post=222"}],"version-history":[{"count":17,"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/pages\/222\/revisions"}],"predecessor-version":[{"id":3635,"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/pages\/222\/revisions\/3635"}],"wp:attachment":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/media?parent=222"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/tags?post=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}