  {"id":1964,"date":"2023-02-21T15:38:14","date_gmt":"2023-02-21T15:38:14","guid":{"rendered":"https:\/\/www.vanderbilt.edu\/evolution\/?p=1964"},"modified":"2023-02-22T05:08:37","modified_gmt":"2023-02-22T05:08:37","slug":"investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas","status":"publish","type":"post","link":"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/","title":{"rendered":"Investigadores de 杏吧原创 Identifican M\u00e9todos de Selecci\u00f3n Natural en Poblaciones Menos Estudiadas"},"content":{"rendered":"<p><em>de Andy Flick, Evolutionary Studies scientific coordinator\u00a0<\/em><\/p>\n<p>Amanda Lea, profesora asistente en biolog\u00eda, con un equipo de expertos globales, han descubierto nuevas secuencias de selecci\u00f3n natural en humanos. El equipo, dirigido por el codirector del Proyecto de Salud y Antropolog\u00eda Tsimane (Tsimane Health and Life History Project) Michael Gurven de la Universidad de California Santa Barbara, estudiaron dos poblaciones que viven en la selva amaz\u00f3nica de Bolivia, los Tsimane y los Moseten. Estudios anteriores muestran que estas poblaciones tropicales est\u00e1n expuestas a muchos par\u00e1sitos y variedad de agentes pat\u00f3genos; y al mismo tiempo los Tsimane raramente sufren de enfermedades cardiovasculares y demencia. Esta investigaci\u00f3n sugiere que el genoma de los Tsimane ha experimentado selecci\u00f3n en rasgos asociados con la inmunidad y el metabolismo. Estos partes del genoma est\u00e1n asociados con la salud de estas poblaciones actualmente.<\/p>\n<p>Esta investigaci\u00f3n a\u00f1ade contexto en la evoluci\u00f3n y especializaci\u00f3n de los humanos en todo el mundo. Pocos ejemplos bien conocidos ya existen. Por ejemplo, los descendentes de los europeos, algunos africanos, y los del oriente medio pueden digerir la lactosa en la edad adulta, lo que mantiene su habilidad de beber leche pasada la pubertad en estas poblaciones.<\/p>\n<p>Seg\u00fan Lea, \u201ca pesar del gran inter\u00e9s en el entendimiento de las variantes de ADN que difieren entre poblaciones de forma adaptiva, todav\u00eda es dif\u00edcil identificar y caracterizar estas variantes. Sin embargo, el trabajo es importante porque podemos descubrir partes de genoma que var\u00edan y son importantes tanto desde la perspectiva evolutiva como biom\u00e9dica\u201d.<\/p>\n<p>Una parte especialmente \u00fanica de este proyecto es que los or\u00edgenes de esta investigaci\u00f3n vienen de una colaboraci\u00f3n entre el Tsimane Health and Life History Project y las comunidades Tsimane y Moseten. Desde hace veinte a\u00f1os, el proyecto ha incluido colaboraciones entre antrop\u00f3logos, m\u00e9dicos, l\u00edderes ind\u00edgenas, miembros de la comunidad e instituciones locales para construir una retrato de su salud y mejorarla. Tales colaboraciones de confianza son vitales para navegar por el panorama \u00e9tico sobre el estudio del ADN en poblaciones ind\u00edgenas.<\/p>\n<p>Sobre la importancia de trabajar con los abor\u00edgenes de Am\u00e9rica del sur, Gurven dijo, \u201cla mayor\u00eda de las investigaciones que conecta mutaciones en el ADN con la salud ha sido en poblaciones europeas o de norte america. Grupos como los Tsimanes tienen una distinta historia viviendo en un distinto ambiente. Es l\u00f3gico que las variantes gen\u00e9ticas \u00fanicas en los Tsimane no existan en las poblaciones m\u00e1s frecuentemente estudiadas. Explorando las variantes \u00fanicas y su relaci\u00f3n a las consecuencias para la salud es algo que estamos haciendo y estamos muy contentos por eso.\u201d<\/p>\n<p>Otro resultado que fue sorprendente para los investigadores, es que al parecer existe una variante beneficiosa que afecta la via en que los Tsimanes usan energ\u00eda. Esto es fascinante porque investigaciones previas sugieren que alelos negativos en poblaciones de los de EEUU o Europa, como la Apolipoproteina-E4 que aumenta el riesgo para la enfermedad de Alzheimer, tengan un efecto positivo en un ambiente con muchos agentes infecciosos y energ\u00eda limitada como es el ambiente en que viven los Tsimane. Estudiando variantes gen\u00e9ticas que afectan la inmunidad, el riesgo de infecci\u00f3n y la salud cardiometabolica pueden favorecer mucho nuestra comprensi\u00f3n sobre porque los alelos da\u00f1inos existen hoy todav\u00eda. Lea explic\u00f3 que los Tsimanes tienen corazones muy fuertes y una linea futura para explorar en estas investigaciones es identificar si las diferencias gen\u00e9ticas en las formas de usar energ\u00eda que fueron encontrada en esta investigaci\u00f3n est\u00e1n relacionadas con la salud cardiovascular y cerebral.<\/p>\n<p>Este proyecto fue realizado con los Tsimanes, una de muchas (mas que 35) grupos ind\u00edgenas de Bolivia. La poblaci\u00f3n de los Tsimanes incluye aproximadamente a 17,000 personas en 90 pueblos. Las muestras de sangre fueron recolectadas de mas que 1,000 personas entre los a\u00f1os 2006 y 2015 por el Tsimane Health and Life History Project. Se recolectaron datos del ADN y informaci\u00f3n sobre polimorfismos de nucle\u00f3tido simple de las muestras de sangre y el equipo identific\u00f3 \u00e1reas del genoma que experimentaron selecci\u00f3n positiva. El equipo us\u00f3 programas estad\u00edsticas y bases de datos en linea para identificar correlaciones en \u00e1reas gen\u00e9ticas relacionadas con la inmunidad. El grupo tambi\u00e9n investig\u00f3 relaciones entre genotipos (genes) y fenotipos (como se expresan esos genes).<\/p>\n<p>En el futuro, el equipo va a explorar otras formas en que los genes de los Tsimane son diferentes a otras poblaciones, como las europeas. Tambi\u00e9n va a construir una rica referencia de la poblaci\u00f3n Tsimane usando otras t\u00e9cnicas biom\u00e9dicas (por ejemplo, transcript\u00f3mica, metabol\u00f3mica y microbioma) para conectar la gen\u00e9tica con la salud.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-1958\" src=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/02\/20023146\/Communication_main_results_v2.png\" alt=\"\" width=\"4328\" height=\"5548\" srcset=\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/02\/20023146\/Communication_main_results_v2.png 4328w, https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/02\/20023146\/Communication_main_results_v2-234x300.png 234w, https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/02\/20023146\/Communication_main_results_v2-799x1024.png 799w, https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/02\/20023146\/Communication_main_results_v2-768x984.png 768w, https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/02\/20023146\/Communication_main_results_v2-1198x1536.png 1198w, https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/02\/20023146\/Communication_main_results_v2-1598x2048.png 1598w\" sizes=\"(max-width: 4328px) 100vw, 4328px\" \/><\/p>\n<p>Parte arriba: Las poblaciones Tsimanes y Moseten han experimentada una carga diversa de pat\u00f3genos durante muchas generaciones. Nuestras investigaciones sugieren que estas enfermedades se han seleccionada para variadas gen\u00e9ticas conectada a inmunidad y metabolismo. Parte abajo: Partes de la genoma que estuvieron seleccionadas a trav\u00e9s del tiempo evolucionario son asociadas con variabilidad en rasgos de salud en los Tsimane (espec\u00edficamente inmunidad y enfermedad cardiovascular). Cr\u00e9dito de imagen: esta imagen fue creada por Caitlyn Skelton de Designs that Cell con consejos de Amanda Lea y Michael Gurven.<\/p>\n<p>Financiamientos: Este proyecto fue financiado por los Institutos Nacionales de Salud, becas R01AG024119, R56AG024119, y RF1AG054442. Este proyecto fue posible gracias al Tsimane Health and Life History Project y las comunidades Tsimanes y Mosetenes.<\/p>\n<p>Cita: Lea, A.J., Garcia, A., Arevalo, J., Ayroles, J.F., Buetow, K., Cole, S.W., Eid Rodriguez, D., Gutierrez, M., Highland, H.M., Hooper, P.L. and Justice, A., 2023. Natural selection of immune and metabolic genes associated with health in two lowland Bolivian populations. Proceedings of the National Academy of Sciences, 120(1), p.e2207544120.<\/p>\n<p><strong><em>Ayuda de traducci\u00f3n proporcionada por Mike Gurven y Daniel Eid Rodriguez.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>de Andy Flick, Evolutionary Studies scientific coordinator\u00a0 Amanda Lea, profesora asistente en biolog\u00eda, con un equipo de expertos globales, han descubierto nuevas secuencias de selecci\u00f3n natural en humanos. El equipo, dirigido por el codirector del Proyecto de Salud y Antropolog\u00eda Tsimane (Tsimane Health and Life History Project) Michael Gurven de la Universidad de California Santa&#8230;<\/p>\n","protected":false},"author":2421,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[1],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investigadores de 杏吧原创 Identifican M\u00e9todos de Selecci\u00f3n Natural en Poblaciones Menos Estudiadas - Evolution@杏吧原创\" \/>\n<meta property=\"og:description\" content=\"de Andy Flick, Evolutionary Studies scientific coordinator\u00a0 Amanda Lea, profesora asistente en biolog\u00eda, con un equipo de expertos globales, han descubierto nuevas secuencias de selecci\u00f3n natural en humanos. El equipo, dirigido por el codirector del Proyecto de Salud y Antropolog\u00eda Tsimane (Tsimane Health and Life History Project) Michael Gurven de la Universidad de California Santa...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolution@杏吧原创\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-21T15:38:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-22T05:08:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vanderbilt.edu\/evolution\/wp-content\/uploads\/sites\/295\/2023\/02\/Communication_main_results_v2.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"flickaj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/#website\",\"url\":\"https:\/\/www.vanderbilt.edu\/evolution\/\",\"name\":\"Evolution@杏吧原创\",\"description\":\"Evolutionary Studies Initiative at 杏吧原创\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vanderbilt.edu\/evolution\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/02\/20023146\/Communication_main_results_v2.png\",\"contentUrl\":\"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/02\/20023146\/Communication_main_results_v2.png\",\"width\":4328,\"height\":5548},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/#webpage\",\"url\":\"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/\",\"name\":\"Investigadores de 杏吧原创 Identifican M\u00e9todos de Selecci\u00f3n Natural en Poblaciones Menos Estudiadas - Evolution@杏吧原创\",\"isPartOf\":{\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/#primaryimage\"},\"datePublished\":\"2023-02-21T15:38:14+00:00\",\"dateModified\":\"2023-02-22T05:08:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/#\/schema\/person\/4607d1feb9ff7141c6d0553b57135f04\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vanderbilt.edu\/evolution\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investigadores de 杏吧原创 Identifican M\u00e9todos de Selecci\u00f3n Natural en Poblaciones Menos Estudiadas\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/#\/schema\/person\/4607d1feb9ff7141c6d0553b57135f04\",\"name\":\"flickaj\",\"url\":\"https:\/\/www.vanderbilt.edu\/evolution\/author\/flickaj\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/","og_locale":"en_US","og_type":"article","og_title":"Investigadores de 杏吧原创 Identifican M\u00e9todos de Selecci\u00f3n Natural en Poblaciones Menos Estudiadas - Evolution@杏吧原创","og_description":"de Andy Flick, Evolutionary Studies scientific coordinator\u00a0 Amanda Lea, profesora asistente en biolog\u00eda, con un equipo de expertos globales, han descubierto nuevas secuencias de selecci\u00f3n natural en humanos. El equipo, dirigido por el codirector del Proyecto de Salud y Antropolog\u00eda Tsimane (Tsimane Health and Life History Project) Michael Gurven de la Universidad de California Santa...","og_url":"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/","og_site_name":"Evolution@杏吧原创","article_published_time":"2023-02-21T15:38:14+00:00","article_modified_time":"2023-02-22T05:08:37+00:00","og_image":[{"url":"https:\/\/www.vanderbilt.edu\/evolution\/wp-content\/uploads\/sites\/295\/2023\/02\/Communication_main_results_v2.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"flickaj","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.vanderbilt.edu\/evolution\/#website","url":"https:\/\/www.vanderbilt.edu\/evolution\/","name":"Evolution@杏吧原创","description":"Evolutionary Studies Initiative at 杏吧原创","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vanderbilt.edu\/evolution\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/#primaryimage","inLanguage":"en-US","url":"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/02\/20023146\/Communication_main_results_v2.png","contentUrl":"https:\/\/cdn.vanderbilt.edu\/vu-URL\/wp-content\/uploads\/sites\/295\/2023\/02\/20023146\/Communication_main_results_v2.png","width":4328,"height":5548},{"@type":"WebPage","@id":"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/#webpage","url":"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/","name":"Investigadores de 杏吧原创 Identifican M\u00e9todos de Selecci\u00f3n Natural en Poblaciones Menos Estudiadas - Evolution@杏吧原创","isPartOf":{"@id":"https:\/\/www.vanderbilt.edu\/evolution\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/#primaryimage"},"datePublished":"2023-02-21T15:38:14+00:00","dateModified":"2023-02-22T05:08:37+00:00","author":{"@id":"https:\/\/www.vanderbilt.edu\/evolution\/#\/schema\/person\/4607d1feb9ff7141c6d0553b57135f04"},"breadcrumb":{"@id":"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vanderbilt.edu\/evolution\/investigadores-de-vanderbilt-university-identifican-metodos-de-seleccion-natural-en-poblaciones-menos-estudiadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vanderbilt.edu\/evolution\/"},{"@type":"ListItem","position":2,"name":"Investigadores de 杏吧原创 Identifican M\u00e9todos de Selecci\u00f3n Natural en Poblaciones Menos Estudiadas"}]},{"@type":"Person","@id":"https:\/\/www.vanderbilt.edu\/evolution\/#\/schema\/person\/4607d1feb9ff7141c6d0553b57135f04","name":"flickaj","url":"https:\/\/www.vanderbilt.edu\/evolution\/author\/flickaj\/"}]}},"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pbblkY-vG","_links":{"self":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/posts\/1964"}],"collection":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/users\/2421"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/comments?post=1964"}],"version-history":[{"count":4,"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/posts\/1964\/revisions"}],"predecessor-version":[{"id":1969,"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/posts\/1964\/revisions\/1969"}],"wp:attachment":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/media?parent=1964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/categories?post=1964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/tags?post=1964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}