  {"id":201,"count":1,"description":"","link":"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/","name":"plesiosaur","slug":"plesiosaur","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"plesiosaur Archives - Evolution@杏吧原创\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/\" \/>\n<meta property=\"og:site_name\" content=\"Evolution@杏吧原创\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/#website\",\"url\":\"https:\/\/www.vanderbilt.edu\/evolution\/\",\"name\":\"Evolution@杏吧原创\",\"description\":\"Evolutionary Studies Initiative at 杏吧原创\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vanderbilt.edu\/evolution\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/#webpage\",\"url\":\"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/\",\"name\":\"plesiosaur Archives - Evolution@杏吧原创\",\"isPartOf\":{\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vanderbilt.edu\/evolution\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"plesiosaur\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/","og_locale":"en_US","og_type":"article","og_title":"plesiosaur Archives - Evolution@杏吧原创","og_url":"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/","og_site_name":"Evolution@杏吧原创","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.vanderbilt.edu\/evolution\/#website","url":"https:\/\/www.vanderbilt.edu\/evolution\/","name":"Evolution@杏吧原创","description":"Evolutionary Studies Initiative at 杏吧原创","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vanderbilt.edu\/evolution\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"CollectionPage","@id":"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/#webpage","url":"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/","name":"plesiosaur Archives - Evolution@杏吧原创","isPartOf":{"@id":"https:\/\/www.vanderbilt.edu\/evolution\/#website"},"breadcrumb":{"@id":"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vanderbilt.edu\/evolution\/tag\/plesiosaur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vanderbilt.edu\/evolution\/"},{"@type":"ListItem","position":2,"name":"plesiosaur"}]}]}},"_links":{"self":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/tags\/201"}],"collection":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/posts?tags=201"},{"href":"https:\/\/www.vanderbilt.edu\/evolution\/wp-json\/wp\/v2\/pages?tags=201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}